{"id":905,"date":"2023-04-03T06:28:21","date_gmt":"2023-04-03T06:28:21","guid":{"rendered":"https:\/des-endroits-a-visiter\/"},"modified":"2023-06-11T12:52:06","modified_gmt":"2023-06-11T12:52:06","slug":"des-endroits-a-visiter","status":"publish","type":"page","link":"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/","title":{"rendered":"Des endroits \u00e0 visiter"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"905\" class=\"elementor elementor-905\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3dae090 e-con-full e-flex e-con e-parent\" data-id=\"3dae090\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-405b9cf elementor-widget elementor-widget-image\" data-id=\"405b9cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"400\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_3_.webp\" class=\"attachment-full size-full wp-image-1834\" alt=\"\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_3_.webp 2000w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_3_-300x60.webp 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_3_-1024x205.webp 1024w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_3_-768x154.webp 768w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_3_-1536x307.webp 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78e757f e-flex e-con-boxed e-con e-parent\" data-id=\"78e757f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb98a5 elementor-widget elementor-widget-heading\" data-id=\"6cb98a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Des endroits \u00e0 visiter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57c6d68 elementor-widget elementor-widget-text-editor\" data-id=\"57c6d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Vous avez de nombreux endroits \u00e0 visiter autour de l&rsquo;H\u00f4tel, nous en donnons ici une s\u00e9lection, pour diff\u00e9rents go\u00fbts et \u00e2ges. Vous ne vous lasserez pas de visiter les meilleurs endroits d&rsquo;Andalousie.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f18bef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f18bef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cffac4\" data-id=\"2cffac4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-33ec487 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33ec487\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c94a89d e-flex e-con-boxed e-con e-parent\" data-id=\"c94a89d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e2a850f e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"e2a850f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98c4eae elementor-widget elementor-widget-heading\" data-id=\"98c4eae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chevaux andalous<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cafd5d4 elementor-widget elementor-widget-text-editor\" data-id=\"cafd5d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Plongez dans la gr\u00e2ce et la noblesse du cheval andalou lors d&rsquo;une promenade relaxante. Connectez-vous avec la nature tout en vous laissant emporter par l&rsquo;\u00e9l\u00e9gance de cette race embl\u00e9matique. Profitez d&rsquo;une balade inoubliable, o\u00f9 vous pourrez appr\u00e9cier leur allure imposante et ressentir l&rsquo;harmonie entre le cavalier et le cheval.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8bfb194 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"8bfb194\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d37419f elementor-widget elementor-widget-image\" data-id=\"d37419f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"565\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/palmar-caballo.jpeg\" class=\"attachment-large size-large wp-image-2717\" alt=\"\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/palmar-caballo.jpeg 900w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/palmar-caballo-300x212.jpeg 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/palmar-caballo-768x543.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f318c31 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f318c31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bb2acfe\" data-id=\"bb2acfe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0138c29 elementor-widget elementor-widget-image\" data-id=\"0138c29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/elementor\/thumbs\/Captura-de-Pantalla-2023-05-24-a-las-12.10.42-1-1-q6xjgyszbbtzkj9jeog6z943p8ke230pi20sz204r6.png\" title=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" alt=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e483f74 e-flex e-con-boxed e-con e-parent\" data-id=\"e483f74\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-55adaf2 e-con-full e-flex e-con e-child\" data-id=\"55adaf2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d00cb elementor-invisible elementor-widget elementor-widget-image\" data-id=\"c2d00cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_5_-1024x683.webp\" class=\"attachment-large size-large wp-image-1846\" alt=\"Lugares para visitar en Andaluc\u00eda\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_5_-1024x683.webp 1024w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_5_-300x200.webp 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_5_-768x512.webp 768w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_5_.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0686356 e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"0686356\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-092405d elementor-widget elementor-widget-heading\" data-id=\"092405d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un jour \u00e0 S\u00e9ville<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c85bf78 elementor-widget elementor-widget-text-editor\" data-id=\"c85bf78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 seulement une heure et demie de l&rsquo;h\u00f4tel se trouve S\u00e9ville, qui regorge d&rsquo;histoire \u00e0 visiter en plus d&rsquo;une journ\u00e9e. Les sites incontournables sont le Real Alc\u00e1zar, un imposant palais mauresque, la cath\u00e9drale, la plus grande \u00e9glise gothique du monde, et l&rsquo;Archivo de Indias, class\u00e9 au patrimoine mondial de l&rsquo;humanit\u00e9 depuis 1987. Le quartier de Santa Cruz, l&rsquo;ancien quartier juif, se trouve \u00e0 proximit\u00e9. Promenez-vous dans le parc Maria Luisa et la Plaza de Espa\u00f1a. Ne manquez pas le mus\u00e9e des beaux-arts pour admirer les peintures baroques s\u00e9villanes.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77ddb3f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"77ddb3f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00d147f\" data-id=\"00d147f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fd8383 elementor-widget elementor-widget-image\" data-id=\"6fd8383\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/elementor\/thumbs\/Captura-de-Pantalla-2023-05-24-a-las-12.10.42-1-1-q6xjgyszbbtzkj9jeog6z943p8ke230pi20sz204r6.png\" title=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" alt=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d07b889 e-flex e-con-boxed e-con e-parent\" data-id=\"d07b889\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2c49f93 e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"2c49f93\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a35090b elementor-widget elementor-widget-heading\" data-id=\"a35090b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parc naturel de Grazalema<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a14b3e elementor-widget elementor-widget-text-editor\" data-id=\"7a14b3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une bonne occasion de profiter d&rsquo;un grand spectacle de la nature, des for\u00eats de pins et de ch\u00eanes-li\u00e8ges, des sommets de plus de 1600 m\u00e8tres, des canyons, des grottes, des vall\u00e9es&#8230; Le tout parsem\u00e9 de pittoresques villages blancs, comme Grazalema avec ses rues pav\u00e9es o\u00f9 l&rsquo;on peut acheter de l&rsquo;artisanat local ; Zahara de la Sierra et visiter son ch\u00e2teau d&rsquo;origine arabe ; Arcos de la Frontera, l&rsquo;un des villages blancs les plus c\u00e9l\u00e8bres o\u00f9 l&rsquo;on peut d\u00e9guster ses fameuses brioches.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e77214 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"7e77214\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a409654 elementor-widget elementor-widget-image\" data-id=\"a409654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-17-2-1024x683.webp\" class=\"attachment-large size-large wp-image-1961\" alt=\"Lugares para visitar en Andaluc\u00eda\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-17-2-1024x683.webp 1024w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-17-2-300x200.webp 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-17-2-768x512.webp 768w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-17-2.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a07c760 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a07c760\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72270a3\" data-id=\"72270a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d07633 elementor-widget elementor-widget-image\" data-id=\"4d07633\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/elementor\/thumbs\/Captura-de-Pantalla-2023-05-24-a-las-12.10.42-1-1-q6xjgyszbbtzkj9jeog6z943p8ke230pi20sz204r6.png\" title=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" alt=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-4ad1d7c e-flex e-con-boxed e-con e-parent\" data-id=\"4ad1d7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-44332b2 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"44332b2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c307939 elementor-widget elementor-widget-image\" data-id=\"c307939\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-23.webp\" class=\"attachment-large size-large wp-image-1991\" alt=\"Lugares para visitar en Andaluc\u00eda\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-23.webp 800w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-23-300x225.webp 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-23-768x576.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c7e7df e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"7c7e7df\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b0c232 elementor-widget elementor-widget-heading\" data-id=\"2b0c232\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un jour \u00e0 Cadix<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65cabe6 elementor-widget elementor-widget-text-editor\" data-id=\"65cabe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consid\u00e9r\u00e9e comme la plus ancienne ville d&rsquo;Europe, Cadix offre de nombreuses attractions qui ne vous d\u00e9cevront pas. La vieille ville, consid\u00e9r\u00e9e comme un monument historico-artistique, m\u00e9rite une promenade. Vous serez au m\u00eame endroit que celui qui a vu le deuxi\u00e8me voyage du<br \/>Christophe Colomb et vous remarquerez, en raison du commerce que cette ville a entretenu avec l&rsquo;Am\u00e9rique, l&rsquo;influence qu&rsquo;il a laiss\u00e9e sur l&rsquo;architecture et le caract\u00e8re de Cadix. La cath\u00e9drale, le mus\u00e9e arch\u00e9ologique et l&rsquo;oratoire de San Felipe Neri valent la peine d&rsquo;\u00eatre visit\u00e9s.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3289c8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c3289c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d64ddfb\" data-id=\"d64ddfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfc7e5b elementor-widget elementor-widget-image\" data-id=\"cfc7e5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/elementor\/thumbs\/Captura-de-Pantalla-2023-05-24-a-las-12.10.42-1-1-q6xjgyszbbtzkj9jeog6z943p8ke230pi20sz204r6.png\" title=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" alt=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ccbb1a3 e-flex e-con-boxed e-con e-parent\" data-id=\"ccbb1a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e46eae7 e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"e46eae7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8924294 elementor-widget elementor-widget-heading\" data-id=\"8924294\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une visite \u00e0 Medina Sidonia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-918947f elementor-widget elementor-widget-text-editor\" data-id=\"918947f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Magnifique village perch\u00e9, maisons blanches avec fer forg\u00e9 et cours int\u00e9rieures. Visite de l&rsquo;\u00e9glise gothique de Santa Maria la Coronada, avec son retable grandiose. L&rsquo;ascension de la tour offre des vues spectaculaires. Medina Sidonia, le balcon de Cadix, offre une vue magnifique sur la baie. Nom d&rsquo;un important duch\u00e9 et de son VIIe duc, D. Alonso Perez de Guzm\u00e1n, qui dirigea l&rsquo;Invincible Armada. Go\u00fbtez aux sucreries et aux alfajores du couvent de San Crist\u00f3bal.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9994070 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"9994070\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b633e37 elementor-widget elementor-widget-image\" data-id=\"b633e37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-8-1024x683.webp\" class=\"attachment-large size-large wp-image-1858\" alt=\"Lugares para visitar en Andaluc\u00eda\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-8-1024x683.webp 1024w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-8-300x200.webp 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-8-768x512.webp 768w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-8.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70199a2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"70199a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf06ae2\" data-id=\"cf06ae2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a66c54 elementor-widget elementor-widget-image\" data-id=\"1a66c54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/elementor\/thumbs\/Captura-de-Pantalla-2023-05-24-a-las-12.10.42-1-1-q6xjgyszbbtzkj9jeog6z943p8ke230pi20sz204r6.png\" title=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" alt=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-fb44d1b e-flex e-con-boxed e-con e-parent\" data-id=\"fb44d1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0162126 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"0162126\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b657a29 elementor-widget elementor-widget-image\" data-id=\"b657a29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_7_-1024x683.webp\" class=\"attachment-large size-large wp-image-1854\" alt=\"Lugares para visitar en Andaluc\u00eda\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_7_-1024x683.webp 1024w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_7_-300x200.webp 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_7_-768x512.webp 768w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-_7_.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a0d55d e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"5a0d55d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40dc175 elementor-widget elementor-widget-heading\" data-id=\"40dc175\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un jour \u00e0 Jerez<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0035b5 elementor-widget elementor-widget-text-editor\" data-id=\"b0035b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jerez est une ville ancienne pleine de vie. Berceau des vins c\u00e9l\u00e8bres, vous trouverez des caves \u00e0 visiter telles que Gonzalez Byass, Pedro Domecq et Sandeman. Elle abrite l&rsquo;\u00c9cole royale andalouse d&rsquo;art \u00e9questre et le Centre andalou de flamenco. L&rsquo;Alcazar, les bains arabes (avec la tour octogonale et sa camera obscura), le mus\u00e9e arch\u00e9ologique et le palais Domecq valent \u00e9galement le d\u00e9tour. Si vous \u00eates un passionn\u00e9 de course automobile, vous pouvez visiter le Circuito de Jerez, o\u00f9 la plupart des \u00e9quipes de F1 s&rsquo;entra\u00eenent. Enfin, si vous avez des rendez-vous, vous pourrez vous promener \u00e0 la Foire aux chevaux.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83c2c4f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"83c2c4f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7688502\" data-id=\"7688502\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33e9258 elementor-widget elementor-widget-image\" data-id=\"33e9258\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/elementor\/thumbs\/Captura-de-Pantalla-2023-05-24-a-las-12.10.42-1-1-q6xjgyszbbtzkj9jeog6z943p8ke230pi20sz204r6.png\" title=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" alt=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-536cbec e-flex e-con-boxed e-con e-parent\" data-id=\"536cbec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-abeb68b e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"abeb68b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8273e2f elementor-widget elementor-widget-heading\" data-id=\"8273e2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visite \u00e0 Acualand<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7dd451 elementor-widget elementor-widget-text-editor\" data-id=\"a7dd451\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Parc aquatique situ\u00e9 entre Puerto de Santa Maria et Jerez.<br \/>qui vous permettront de vous amuser toute la journ\u00e9e. Parmi les nombreuses attractions, citons les Rapides, la Crazy Race, Kamikaze, une plage de surf avec des vagues artificielles, ainsi qu&rsquo;un centre de loisirs.<br \/>Il dispose d&rsquo;un restaurant et d&rsquo;un bar. L&rsquo;un des endroits pr\u00e9f\u00e9r\u00e9s des enfants en Andalousie.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-afd4cb1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"afd4cb1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d403f2 elementor-widget elementor-widget-image\" data-id=\"9d403f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-10-1024x683.webp\" class=\"attachment-large size-large wp-image-1873\" alt=\"Lugares para visitar en Andaluc\u00eda\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-10-1024x683.webp 1024w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-10-300x200.webp 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-10-768x512.webp 768w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-10.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-337f835 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"337f835\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99f7f60\" data-id=\"99f7f60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee6f408 elementor-widget elementor-widget-image\" data-id=\"ee6f408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/elementor\/thumbs\/Captura-de-Pantalla-2023-05-24-a-las-12.10.42-1-1-q6xjgyszbbtzkj9jeog6z943p8ke230pi20sz204r6.png\" title=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" alt=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a6f56d2 e-flex e-con-boxed e-con e-parent\" data-id=\"a6f56d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a049fb7 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"a049fb7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02a1c40 elementor-widget elementor-widget-image\" data-id=\"02a1c40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-11-1024x683.webp\" class=\"attachment-large size-large wp-image-1881\" alt=\"Lugares para visitar en Andaluc\u00eda\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-11-1024x683.webp 1024w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-11-300x200.webp 300w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-11-768x512.webp 768w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-11.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a196a60 e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"a196a60\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c26911 elementor-widget elementor-widget-heading\" data-id=\"2c26911\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un petit tour en Afrique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53f3fbb elementor-widget elementor-widget-text-editor\" data-id=\"53f3fbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;Afrique n&rsquo;est jamais loin de la Costa de la Luz, de nombreux endroits de la c\u00f4te, vous pourrez voir les montagnes du nord si proches qu&rsquo;elles se touchent presque.<\/p>\n<p>Depuis Tarifa, vous pouvez prendre un ferry rapide pour Tanger et, en 35 minutes, vous \u00eates sur un autre continent. Si vous le souhaitez, vous pouvez r\u00e9server une visite guid\u00e9e qui comprend un aller-retour le m\u00eame jour, une visite de la ville en bus, un repas marocain traditionnel et une visite du souk.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf337c8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cf337c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1118ff7\" data-id=\"1118ff7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e5067a elementor-widget elementor-widget-image\" data-id=\"0e5067a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/elementor\/thumbs\/Captura-de-Pantalla-2023-05-24-a-las-12.10.42-1-1-q6xjgyszbbtzkj9jeog6z943p8ke230pi20sz204r6.png\" title=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" alt=\"Captura de Pantalla 2023-05-24 a las 12.10.42 (1) (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6270c90 e-flex e-con-boxed e-con e-parent\" data-id=\"6270c90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-810cd1c e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"810cd1c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ebcb0f elementor-widget elementor-widget-heading\" data-id=\"9ebcb0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Observer les dauphins et les baleines<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e7d8e2 elementor-widget elementor-widget-text-editor\" data-id=\"0e7d8e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous vous rendez \u00e0 Tarifa, vous pourrez prendre un bateau de plaisance pendant quelques heures pour observer les dauphins, les orques et les baleines. Une exp\u00e9rience unique et \u00e9ducative.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eeffd0f e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"eeffd0f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a030eb elementor-widget elementor-widget-image\" data-id=\"8a030eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"399\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/tumares.webp\" class=\"attachment-full size-full wp-image-3194\" alt=\"Lugares para visitar en Andaluc\u00eda\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/tumares.webp 650w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/tumares-300x184.webp 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-314ee58 e-flex e-con-boxed e-con e-parent\" data-id=\"314ee58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3781250 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3781250\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bcc661 elementor-widget elementor-widget-image\" data-id=\"0bcc661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"433\" src=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-06-at-13.06.14-2.webp\" class=\"attachment-large size-large wp-image-2858\" alt=\"Lugares para visitar en Andalucia\" srcset=\"https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-06-at-13.06.14-2.webp 650w, https:\/\/hotelsindhura.com\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-06-at-13.06.14-2-300x200.webp 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c460ebf e-con-full contenedor e-flex elementor-invisible e-con e-child\" data-id=\"c460ebf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4863270 elementor-widget elementor-widget-heading\" data-id=\"4863270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un petit tour en Afrique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eda26ec elementor-widget elementor-widget-text-editor\" data-id=\"eda26ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;Afrique n&rsquo;est jamais loin de la Costa de la Luz, de nombreux endroits de la c\u00f4te, vous pourrez voir les montagnes du nord si proches qu&rsquo;elles se touchent presque.<\/p>\n<p>Depuis Tarifa, vous pouvez prendre un ferry rapide pour Tanger et, en 35 minutes, vous \u00eates sur un autre continent. Si vous le souhaitez, vous pouvez r\u00e9server une visite guid\u00e9e qui comprend un aller-retour le m\u00eame jour, une visite de la ville en bus, un repas marocain traditionnel et une visite du souk.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Des endroits \u00e0 visiter Vous avez de nombreux endroits \u00e0 visiter autour de l&rsquo;H\u00f4tel, nous en donnons ici une s\u00e9lection, pour diff\u00e9rents go\u00fbts et \u00e2ges. Vous ne vous lasserez pas de visiter les meilleurs endroits d&rsquo;Andalousie. Chevaux andalous Plongez dans la gr\u00e2ce et la noblesse du cheval andalou lors d&rsquo;une promenade relaxante. Connectez-vous avec la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-905","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lieux \u00e0 visiter en Andalousie<\/title>\n<meta name=\"description\" content=\"Lieux \u00e0 visiter en Andalousie, depuis l&#039;h\u00f4tel Sindhura, il est tr\u00e8s facile de se d\u00e9placer entre diff\u00e9rents lieux merveilleux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lieux \u00e0 visiter en Andalousie\" \/>\n<meta property=\"og:description\" content=\"Lieux \u00e0 visiter en Andalousie, depuis l&#039;h\u00f4tel Sindhura, il est tr\u00e8s facile de se d\u00e9placer entre diff\u00e9rents lieux merveilleux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Sindhura\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-11T12:52:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/\",\"url\":\"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/\",\"name\":\"Lieux \u00e0 visiter en Andalousie\",\"isPartOf\":{\"@id\":\"https:\/\/www.hotelsindhura.com\/fr\/#website\"},\"datePublished\":\"2023-04-03T06:28:21+00:00\",\"dateModified\":\"2023-06-11T12:52:06+00:00\",\"description\":\"Lieux \u00e0 visiter en Andalousie, depuis l'h\u00f4tel Sindhura, il est tr\u00e8s facile de se d\u00e9placer entre diff\u00e9rents lieux merveilleux.\",\"breadcrumb\":{\"@id\":\"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.hotelsindhura.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des endroits \u00e0 visiter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hotelsindhura.com\/fr\/#website\",\"url\":\"https:\/\/www.hotelsindhura.com\/fr\/\",\"name\":\"Hotel Sindhura\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.hotelsindhura.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hotelsindhura.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hotelsindhura.com\/fr\/#organization\",\"name\":\"Hotel Sindhura\",\"alternateName\":\"Hotel Sindhura\",\"url\":\"https:\/\/www.hotelsindhura.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.hotelsindhura.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"\/\/\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-05-at-12.35.42.jpeg\",\"contentUrl\":\"\/\/\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-05-at-12.35.42.jpeg\",\"width\":1064,\"height\":1428,\"caption\":\"Hotel Sindhura\"},\"image\":{\"@id\":\"https:\/\/www.hotelsindhura.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lieux \u00e0 visiter en Andalousie","description":"Lieux \u00e0 visiter en Andalousie, depuis l'h\u00f4tel Sindhura, il est tr\u00e8s facile de se d\u00e9placer entre diff\u00e9rents lieux merveilleux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/","og_locale":"fr_FR","og_type":"article","og_title":"Lieux \u00e0 visiter en Andalousie","og_description":"Lieux \u00e0 visiter en Andalousie, depuis l'h\u00f4tel Sindhura, il est tr\u00e8s facile de se d\u00e9placer entre diff\u00e9rents lieux merveilleux.","og_url":"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/","og_site_name":"Hotel Sindhura","article_modified_time":"2023-06-11T12:52:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/","url":"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/","name":"Lieux \u00e0 visiter en Andalousie","isPartOf":{"@id":"https:\/\/www.hotelsindhura.com\/fr\/#website"},"datePublished":"2023-04-03T06:28:21+00:00","dateModified":"2023-06-11T12:52:06+00:00","description":"Lieux \u00e0 visiter en Andalousie, depuis l'h\u00f4tel Sindhura, il est tr\u00e8s facile de se d\u00e9placer entre diff\u00e9rents lieux merveilleux.","breadcrumb":{"@id":"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotelsindhura.com\/fr\/des-endroits-a-visiter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hotelsindhura.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Des endroits \u00e0 visiter"}]},{"@type":"WebSite","@id":"https:\/\/www.hotelsindhura.com\/fr\/#website","url":"https:\/\/www.hotelsindhura.com\/fr\/","name":"Hotel Sindhura","description":"","publisher":{"@id":"https:\/\/www.hotelsindhura.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotelsindhura.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.hotelsindhura.com\/fr\/#organization","name":"Hotel Sindhura","alternateName":"Hotel Sindhura","url":"https:\/\/www.hotelsindhura.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hotelsindhura.com\/fr\/#\/schema\/logo\/image\/","url":"\/\/\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-05-at-12.35.42.jpeg","contentUrl":"\/\/\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-05-at-12.35.42.jpeg","width":1064,"height":1428,"caption":"Hotel Sindhura"},"image":{"@id":"https:\/\/www.hotelsindhura.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotelsindhura.com\/fr\/wp-json\/wp\/v2\/pages\/905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelsindhura.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotelsindhura.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotelsindhura.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelsindhura.com\/fr\/wp-json\/wp\/v2\/comments?post=905"}],"version-history":[{"count":20,"href":"https:\/\/hotelsindhura.com\/fr\/wp-json\/wp\/v2\/pages\/905\/revisions"}],"predecessor-version":[{"id":3204,"href":"https:\/\/hotelsindhura.com\/fr\/wp-json\/wp\/v2\/pages\/905\/revisions\/3204"}],"wp:attachment":[{"href":"https:\/\/hotelsindhura.com\/fr\/wp-json\/wp\/v2\/media?parent=905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}